{"id":8558,"count":3,"description":"","link":"https:\/\/www.petersons.com\/blog\/tag\/educators\/","name":"educators","slug":"educators","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>educators Archives - Peterson&#039;s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.petersons.com\/blog\/tag\/educators\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"educators Archives - Peterson&#039;s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.petersons.com\/blog\/tag\/educators\/\" \/>\n<meta property=\"og:site_name\" content=\"Peterson&#039;s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Petersons\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"educators Archives - Peterson&#039;s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.petersons.com\/blog\/tag\/educators\/","og_locale":"en_US","og_type":"article","og_title":"educators Archives - Peterson&#039;s","og_url":"https:\/\/www.petersons.com\/blog\/tag\/educators\/","og_site_name":"Peterson&#039;s","twitter_card":"summary_large_image","twitter_site":"@Petersons","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.petersons.com\/blog\/tag\/educators\/","url":"https:\/\/www.petersons.com\/blog\/tag\/educators\/","name":"educators Archives - Peterson&#039;s","isPartOf":{"@id":"https:\/\/www.petersons.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.petersons.com\/blog\/tag\/educators\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.petersons.com\/blog\/tag\/educators\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.petersons.com\/blog\/"},{"@type":"ListItem","position":2,"name":"educators"}]},{"@type":"WebSite","@id":"https:\/\/www.petersons.com\/blog\/#website","url":"https:\/\/www.petersons.com\/blog\/","name":"Peterson&#039;s","description":"Peterson&#039;s helps students discover their best fit educational program","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.petersons.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.petersons.com\/blog\/wp-json\/wp\/v2\/tags\/8558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.petersons.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.petersons.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.petersons.com\/blog\/wp-json\/wp\/v2\/posts?tags=8558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}